{"id":6657,"date":"2025-12-03T18:36:09","date_gmt":"2025-12-03T17:36:09","guid":{"rendered":"https:\/\/dev.breinco.com\/?post_type=proyecto&#038;p=6657"},"modified":"2026-03-03T11:23:41","modified_gmt":"2026-03-03T10:23:41","slug":"pavimento-descontaminante-en-la-avenida-icaria","status":"publish","type":"proyecto","link":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/","title":{"rendered":"Pavimento descontaminante en la Avenida Icaria"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Renovaci\u00f3n urbana con pavimento descontaminante AirClean\u00ae<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ubicada en el barrio de la Vila Ol\u00edmpica, la Avenida Icaria ha experimentado una renovaci\u00f3n integral de su rambla central, transformando 8.000\u202fm\u00b2 de espacio p\u00fablico en un entorno m\u00e1s accesible, sostenible y acogedor. El proyecto ha respetado la estructura original del paseo, potenciando su car\u00e1cter urbano mediante mejoras en iluminaci\u00f3n, mobiliario y recorridos peatonales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pavimento juega un papel clave en la intervenci\u00f3n. Se incorpor\u00f3 un <strong>sistema fotocatal\u00edtico Air Clean\u00ae<\/strong> en formato 60x40x7\u202fcm que contribuye a <strong>reducir la contaminaci\u00f3n atmosf\u00e9rica<\/strong>, transformando los \u00f3xidos de nitr\u00f3geno (NOx) en compuestos inocuos mediante la acci\u00f3n de la luz solar y el agua. Esta tecnolog\u00eda permite generar superficies m\u00e1s saludables y autolimpiables, integr\u00e1ndose de forma natural en el dise\u00f1o urbano sin alterar la est\u00e9tica de la rambla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para reforzar la accesibilidad, se incorporaron <strong>pavimentos podot\u00e1ctiles que se\u00f1alan cruces y desniveles<\/strong>, facilitando la movilidad de personas con discapacidad visual y aportando seguridad e inclusi\u00f3n a todo el recorrido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El resultado es un paseo revitalizado que combina sostenibilidad, funcionalidad y confort, recuperando la Avenida Icaria como eje urbano activo y abierto a la vida cotidiana, el comercio y la movilidad peatonal, un ejemplo de c\u00f3mo la renovaci\u00f3n urbana puede mejorar tanto la experiencia de los usuarios como la calidad ambiental de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":6664,"template":"","meta":{"_acf_changed":true},"tags":[96,76,97],"categoria-proyecto":[],"class_list":["post-6657","proyecto","type-proyecto","status-publish","has-post-thumbnail","hentry","tag-crossing","tag-tactile","tag-warning"],"acf":{"localitzacio-projecte":"Barcelona","credits-projecte":"Miquel Espinet | Antoni Ubach","fotografia-projecte":"Uatxut","producte_resum":"Llosa vulcano\u00ae Tactile","producte-projecte":"Llosa vulcano\u00ae | 60 x 40 x 7 cm | Ceniza | Standard\u00ae | Air Clean\u00ae\r\n\r\nLlosa vulcano\u00ae Tactile Warning y Crossing | 60 x 40 x 5 cm | Ceniza | Standard\u00ae | Air Clean\u00ae","productes_relacionats":[3657],"galeria-projecte":[6659,6660,6661,6662,6663]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pavimento descontaminante en la Avenida Icaria - Breinco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pavimento descontaminante en la Avenida Icaria - Breinco\" \/>\n<meta property=\"og:description\" content=\"Renovaci\u00f3n urbana con pavimento descontaminante AirClean\u00ae Ubicada en el barrio de la Vila Ol\u00edmpica, la Avenida Icaria ha experimentado una renovaci\u00f3n integral de su rambla central, transformando 8.000\u202fm\u00b2 de espacio p\u00fablico en un entorno m\u00e1s accesible, sostenible y acogedor. El proyecto ha respetado la estructura original del paseo, potenciando su car\u00e1cter urbano mediante mejoras en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Breinco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/breincosmart\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T10:23:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/breinco.com\/wp-content\/uploads\/2025\/12\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@breincoGroup\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/\",\"url\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/\",\"name\":\"Pavimento descontaminante en la Avenida Icaria - Breinco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/breinco.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg\",\"datePublished\":\"2025-12-03T17:36:09+00:00\",\"dateModified\":\"2026-03-03T10:23:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/breinco.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg\",\"contentUrl\":\"https:\\\/\\\/breinco.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/pavimento-descontaminante-en-la-avenida-icaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/breinco.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/breinco.com\\\/es\\\/proyecto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pavimento descontaminante en la Avenida Icaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/breinco.com\\\/es\\\/\",\"name\":\"Breinco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/#organization\"},\"alternateName\":\"Urban Furniture, Architecture and Landscaping\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/breinco.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/#organization\",\"name\":\"Breinco\",\"url\":\"https:\\\/\\\/breinco.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/breinco.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/breinco-brand.svg\",\"contentUrl\":\"https:\\\/\\\/breinco.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/breinco-brand.svg\",\"width\":26,\"height\":58,\"caption\":\"Breinco\"},\"image\":{\"@id\":\"https:\\\/\\\/breinco.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/breincosmart\\\/\",\"https:\\\/\\\/x.com\\\/breincoGroup\",\"https:\\\/\\\/www.instagram.com\\\/breinco\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/breinco-esp\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pavimento descontaminante en la Avenida Icaria - Breinco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/","og_locale":"es_ES","og_type":"article","og_title":"Pavimento descontaminante en la Avenida Icaria - Breinco","og_description":"Renovaci\u00f3n urbana con pavimento descontaminante AirClean\u00ae Ubicada en el barrio de la Vila Ol\u00edmpica, la Avenida Icaria ha experimentado una renovaci\u00f3n integral de su rambla central, transformando 8.000\u202fm\u00b2 de espacio p\u00fablico en un entorno m\u00e1s accesible, sostenible y acogedor. El proyecto ha respetado la estructura original del paseo, potenciando su car\u00e1cter urbano mediante mejoras en [&hellip;]","og_url":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/","og_site_name":"Breinco","article_publisher":"https:\/\/www.facebook.com\/breincosmart\/","article_modified_time":"2026-03-03T10:23:41+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/breinco.com\/wp-content\/uploads\/2025\/12\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@breincoGroup","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/","url":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/","name":"Pavimento descontaminante en la Avenida Icaria - Breinco","isPartOf":{"@id":"https:\/\/breinco.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/#primaryimage"},"image":{"@id":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/#primaryimage"},"thumbnailUrl":"https:\/\/breinco.com\/wp-content\/uploads\/2025\/12\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg","datePublished":"2025-12-03T17:36:09+00:00","dateModified":"2026-03-03T10:23:41+00:00","breadcrumb":{"@id":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/#primaryimage","url":"https:\/\/breinco.com\/wp-content\/uploads\/2025\/12\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg","contentUrl":"https:\/\/breinco.com\/wp-content\/uploads\/2025\/12\/1-avenida-icaria-warning-corssing-llosa-pavimento-tactile-breinco-1.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/breinco.com\/es\/proyecto\/pavimento-descontaminante-en-la-avenida-icaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/breinco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/breinco.com\/es\/proyecto\/"},{"@type":"ListItem","position":3,"name":"Pavimento descontaminante en la Avenida Icaria"}]},{"@type":"WebSite","@id":"https:\/\/breinco.com\/es\/#website","url":"https:\/\/breinco.com\/es\/","name":"Breinco","description":"","publisher":{"@id":"https:\/\/breinco.com\/es\/#organization"},"alternateName":"Urban Furniture, Architecture and Landscaping","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/breinco.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/breinco.com\/es\/#organization","name":"Breinco","url":"https:\/\/breinco.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/breinco.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/breinco.com\/wp-content\/uploads\/2025\/04\/breinco-brand.svg","contentUrl":"https:\/\/breinco.com\/wp-content\/uploads\/2025\/04\/breinco-brand.svg","width":26,"height":58,"caption":"Breinco"},"image":{"@id":"https:\/\/breinco.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/breincosmart\/","https:\/\/x.com\/breincoGroup","https:\/\/www.instagram.com\/breinco\/","https:\/\/www.linkedin.com\/company\/breinco-esp\/"]}]}},"_links":{"self":[{"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/proyecto\/6657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/proyecto"}],"about":[{"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/types\/proyecto"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media\/6663"},{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media\/6662"},{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media\/6661"},{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media\/6660"},{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media\/6659"}],"acf:post":[{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/br_product\/3657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media\/6664"}],"wp:attachment":[{"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/media?parent=6657"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/tags?post=6657"},{"taxonomy":"categoria-proyecto","embeddable":true,"href":"https:\/\/breinco.com\/es\/wp-json\/wp\/v2\/categoria-proyecto?post=6657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}